{"id":1784,"date":"2025-02-28T19:48:30","date_gmt":"2025-02-28T18:48:30","guid":{"rendered":"https:\/\/unpasdecote.asso.fr\/?page_id=1784"},"modified":"2026-02-18T10:45:35","modified_gmt":"2026-02-18T09:45:35","slug":"saison-sous-chapiteau","status":"publish","type":"page","link":"https:\/\/unpasdecote.asso.fr\/index.php\/saison-sous-chapiteau\/","title":{"rendered":"Saison sous chapiteau"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1784\" class=\"elementor elementor-1784\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0461f6 e-flex e-con-boxed e-con e-parent\" data-id=\"c0461f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e92c80a elementor-grid-eael-col-3 elementor-grid-tablet-eael-col-2 elementor-grid-mobile-eael-col-1 elementor-widget elementor-widget-eael-post-grid\" data-id=\"e92c80a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;eael_post_grid_columns&quot;:&quot;eael-col-3&quot;,&quot;eael_post_grid_columns_tablet&quot;:&quot;eael-col-2&quot;,&quot;eael_post_grid_columns_mobile&quot;:&quot;eael-col-1&quot;}\" data-widget_type=\"eael-post-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"eael-post-grid-e92c80a\" class=\"eael-post-grid-container\">\n            <div class=\"eael-post-grid eael-post-appender eael-post-appender-e92c80a eael-post-grid-style-two\" data-layout-mode=\"grid\"><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-2379 category-page-daccueil-saison-sous-chapiteau\" data-id=\"2379\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/03\/ouverture-de-saison-18-avril\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                            <img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/ti-fil-a-linge-1280-x-720-px-1920-x-1080-px4-300x169.png\" class=\"attachment-medium size-medium wp-image-2390\" alt=\"\" srcset=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/ti-fil-a-linge-1280-x-720-px-1920-x-1080-px4-300x169.png 300w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/ti-fil-a-linge-1280-x-720-px-1920-x-1080-px4-1024x576.png 1024w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/ti-fil-a-linge-1280-x-720-px-1920-x-1080-px4-768x432.png 768w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/ti-fil-a-linge-1280-x-720-px-1920-x-1080-px4-1536x864.png 1536w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/ti-fil-a-linge-1280-x-720-px-1920-x-1080-px4-1320x743.png 1320w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/ti-fil-a-linge-1280-x-720-px-1920-x-1080-px4.png 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n                            <\/div>\n                    <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/03\/ouverture-de-saison-18-avril\/\" title=\"Ouverture de saison 18 avril\">Ouverture de saison 18 avril<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                <div class=\"eael-grid-post-excerpt\"><p>Une...<\/p><\/div>\n                            <\/div><\/div><\/div>\n    <\/div>\n<\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-2395 category-saison-sous-chapiteau\" data-id=\"2395\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/04\/hors-champ-05-06\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                            <img decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/3-300x100.png\" class=\"attachment-medium size-medium wp-image-2562\" alt=\"\" srcset=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/3-300x100.png 300w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/3-1024x341.png 1024w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/3-768x256.png 768w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/3.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n                            <\/div>\n                    <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/04\/hors-champ-05-06\/\" title=\"Hors Champ 08\/05\">Hors Champ 08\/05<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                <div class=\"eael-grid-post-excerpt\"><p>Pour...<\/p><\/div>\n                            <\/div><\/div><\/div>\n    <\/div>\n<\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-2398 category-saison-sous-chapiteau\" data-id=\"2398\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/05\/bissap-19-05\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                            <img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/bissap1-300x300.png\" class=\"attachment-medium size-medium wp-image-2399\" alt=\"\" srcset=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/bissap1-300x300.png 300w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/bissap1-150x150.png 150w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/bissap1-768x768.png 768w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/bissap1.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n                            <\/div>\n                    <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/05\/bissap-19-05\/\" title=\"Bissap 19\/05\">Bissap 19\/05<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                <div class=\"eael-grid-post-excerpt\"><p>Ce...<\/p><\/div>\n                            <\/div><\/div><\/div>\n    <\/div>\n<\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-2565 category-saison-sous-chapiteau\" data-id=\"2565\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/07\/vite-il-est-trop-tard-cirque\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/videur-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2566\" alt=\"\" srcset=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/videur-300x200.jpg 300w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/videur-1024x683.jpg 1024w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/videur-768x512.jpg 768w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/videur-1536x1024.jpg 1536w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/videur-2048x1366.jpg 2048w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/videur-700x465.jpg 700w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/videur-1320x880.jpg 1320w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n                            <\/div>\n                    <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/07\/vite-il-est-trop-tard-cirque\/\" title=\"Vite il est trop tard 22 mai\">Vite il est trop tard 22 mai<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                <div class=\"eael-grid-post-excerpt\"><p>Dans...<\/p><\/div>\n                            <\/div><\/div><\/div>\n    <\/div>\n<\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-2405 category-saison-sous-chapiteau\" data-id=\"2405\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/07\/match-dimpro-les-trous-dbal-23-mai\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Corp-arbitral-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2408\" alt=\"\" srcset=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Corp-arbitral-300x200.jpg 300w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Corp-arbitral-1024x682.jpg 1024w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Corp-arbitral-768x512.jpg 768w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Corp-arbitral-1536x1023.jpg 1536w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Corp-arbitral-700x465.jpg 700w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Corp-arbitral-1320x879.jpg 1320w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Corp-arbitral.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n                            <\/div>\n                    <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/07\/match-dimpro-les-trous-dbal-23-mai\/\" title=\"Match d&rsquo;impro + Les Trous d&rsquo;Bal 23 Mai\">Match d&rsquo;impro + Les Trous d&rsquo;Bal 23 Mai<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                <div class=\"eael-grid-post-excerpt\"><p>18h30...<\/p><\/div>\n                            <\/div><\/div><\/div>\n    <\/div>\n<\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-2570 category-saison-sous-chapiteau\" data-id=\"2570\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/07\/notsobrasil-29-mai\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/05.16-notso-300x135.jpg\" class=\"attachment-medium size-medium wp-image-2571\" alt=\"\" srcset=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/05.16-notso-300x135.jpg 300w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/05.16-notso-1024x460.jpg 1024w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/05.16-notso-768x345.jpg 768w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/05.16-notso-1536x690.jpg 1536w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/05.16-notso-1320x593.jpg 1320w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/04\/05.16-notso.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n                            <\/div>\n                    <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/07\/notsobrasil-29-mai\/\" title=\"Notsobrasil 29 mai\">Notsobrasil 29 mai<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                <div class=\"eael-grid-post-excerpt\"><p>L&rsquo;association...<\/p><\/div>\n                            <\/div><\/div><\/div>\n    <\/div>\n<\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-2410 category-saison-sous-chapiteau\" data-id=\"2410\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/08\/chapiteau-ouvert-06-06\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/01\/chapiteau-ouvert1-300x300.png\" class=\"attachment-medium size-medium wp-image-2412\" alt=\"\" srcset=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/01\/chapiteau-ouvert1-300x300.png 300w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/01\/chapiteau-ouvert1-150x150.png 150w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/01\/chapiteau-ouvert1-768x768.png 768w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/01\/chapiteau-ouvert1.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n                            <\/div>\n                    <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/08\/chapiteau-ouvert-06-06\/\" title=\"Chapiteau ouvert 06\/06\">Chapiteau ouvert 06\/06<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                <div class=\"eael-grid-post-excerpt\"><p>D\u00e9couvrez...<\/p><\/div>\n                            <\/div><\/div><\/div>\n    <\/div>\n<\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-2413 category-non-classe-saison-sous-chapiteau\" data-id=\"2413\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/09\/cie-akabi-cie\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Copie-de-hors-champ-300x300.png\" class=\"attachment-medium size-medium wp-image-2416\" alt=\"\" srcset=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Copie-de-hors-champ-300x300.png 300w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Copie-de-hors-champ-150x150.png 150w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Copie-de-hors-champ-768x768.png 768w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/Copie-de-hors-champ.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n                            <\/div>\n                    <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/09\/cie-akabi-cie\/\" title=\"Cie Akabi + Cie Rockstrong 12\/06\">Cie Akabi + Cie Rockstrong 12\/06<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                <div class=\"eael-grid-post-excerpt\"><p>19h...<\/p><\/div>\n                            <\/div><\/div><\/div>\n    <\/div>\n<\/article><article class=\"eael-grid-post  eael-post-grid-column eael-pg-post-2418 category-saison-sous-chapiteau\" data-id=\"2418\">\n    <div class=\"eael-grid-post-holder\">\n        <div class=\"eael-grid-post-holder-inner\"><div class=\"eael-entry-media\"><div class=\"eael-entry-overlay fade-in\"><i class=\"fas fa-long-arrow-alt-right\" aria-hidden=\"true\"><\/i><a href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/10\/fete-de-la-musique-21-06\/\"><\/a><\/div><div class=\"eael-entry-thumbnail eael-image-ratio\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/fete-de-la-musique1-300x300.png\" class=\"attachment-medium size-medium wp-image-2419\" alt=\"\" srcset=\"https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/fete-de-la-musique1-300x300.png 300w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/fete-de-la-musique1-150x150.png 150w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/fete-de-la-musique1-768x768.png 768w, https:\/\/unpasdecote.asso.fr\/wp-content\/uploads\/2026\/02\/fete-de-la-musique1.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n                            <\/div>\n                    <\/div><div class=\"eael-entry-wrapper\"><header class=\"eael-entry-header\"><h2 class=\"eael-entry-title\"><a class=\"eael-grid-post-link\" href=\"https:\/\/unpasdecote.asso.fr\/index.php\/2026\/02\/10\/fete-de-la-musique-21-06\/\" title=\"F\u00eate de la musique 21\/06\">F\u00eate de la musique 21\/06<\/a><\/h2><\/header><div class=\"eael-entry-content\">\n                                <div class=\"eael-grid-post-excerpt\"><p>Une...<\/p><\/div>\n                            <\/div><\/div><\/div>\n    <\/div>\n<\/article><\/div>\n            <div class=\"clearfix\"><\/div>\n        <\/div>            <div class=\"eael-load-more-button-wrap eael-infinity-scroll\" data-offset=\"-200\">\n                <button class=\"eael-load-more-button\" id=\"eael-load-more-btn-e92c80a\" data-widget-id=\"e92c80a\" data-widget=\"e92c80a\" data-page-id=\"1784\" data-template=\"{&quot;dir&quot;:&quot;lite&quot;,&quot;file_name&quot;:&quot;two.php&quot;,&quot;name&quot;:&quot;Post-Grid&quot;}\" data-class=\"Essential_Addons_Elementor\\Elements\\Post_Grid\" data-layout=\"grid\" data-page=\"1\" data-args=\"orderby=date&amp;order=asc&amp;ignore_sticky_posts=1&amp;post_status=publish&amp;posts_per_page=9&amp;offset=0&amp;post_type=post&amp;tax_query%5B0%5D%5Btaxonomy%5D=category&amp;tax_query%5B0%5D%5Bfield%5D=term_id&amp;tax_query%5B0%5D%5Bterms%5D%5B0%5D=25&amp;tax_query%5Brelation%5D=AND\" data-max-page=\"3\">\n                    <span class=\"eael-btn-loader button__loader\"><\/span>\n                    <span class=\"eael_load_more_text\">Load More<\/span>\n                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Soir\u00e9e spectacle Maloya R\u00e9servations&#8230; Ouverture de saison 18 avril Une&#8230; Hors Champ 08\/05 La&#8230; Bissap 19\/05 Mixant&#8230; Match d&rsquo;impro + Les Trous d&rsquo;Bal 23 Mai &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1784","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/unpasdecote.asso.fr\/index.php\/wp-json\/wp\/v2\/pages\/1784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unpasdecote.asso.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/unpasdecote.asso.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/unpasdecote.asso.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unpasdecote.asso.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1784"}],"version-history":[{"count":25,"href":"https:\/\/unpasdecote.asso.fr\/index.php\/wp-json\/wp\/v2\/pages\/1784\/revisions"}],"predecessor-version":[{"id":2423,"href":"https:\/\/unpasdecote.asso.fr\/index.php\/wp-json\/wp\/v2\/pages\/1784\/revisions\/2423"}],"wp:attachment":[{"href":"https:\/\/unpasdecote.asso.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}